{"id":633,"count":1,"description":"","link":"http:\/\/www.laestaciondeneguri.com\/blog\/tag\/ramiro-pinilla-y-leopoldo-maria-panero\/","name":"Ramiro Pinilla y Leopoldo Mar\u00eda Panero","slug":"ramiro-pinilla-y-leopoldo-maria-panero","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"http:\/\/www.laestaciondeneguri.com\/blog\/wp-json\/wp\/v2\/tags\/633"}],"collection":[{"href":"http:\/\/www.laestaciondeneguri.com\/blog\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"http:\/\/www.laestaciondeneguri.com\/blog\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"http:\/\/www.laestaciondeneguri.com\/blog\/wp-json\/wp\/v2\/posts?tags=633"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}