{"id":1424,"count":1,"description":"","link":"http:\/\/www.laestaciondeneguri.com\/blog\/tag\/julian-lynch\/","name":"Julian Lynch","slug":"julian-lynch","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"http:\/\/www.laestaciondeneguri.com\/blog\/wp-json\/wp\/v2\/tags\/1424"}],"collection":[{"href":"http:\/\/www.laestaciondeneguri.com\/blog\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"http:\/\/www.laestaciondeneguri.com\/blog\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"http:\/\/www.laestaciondeneguri.com\/blog\/wp-json\/wp\/v2\/posts?tags=1424"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}