{"id":1186,"count":1,"description":"","link":"http:\/\/www.laestaciondeneguri.com\/blog\/tag\/la-tarde-de-la-ira\/","name":"La tarde de la ira","slug":"la-tarde-de-la-ira","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"http:\/\/www.laestaciondeneguri.com\/blog\/wp-json\/wp\/v2\/tags\/1186"}],"collection":[{"href":"http:\/\/www.laestaciondeneguri.com\/blog\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"http:\/\/www.laestaciondeneguri.com\/blog\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"http:\/\/www.laestaciondeneguri.com\/blog\/wp-json\/wp\/v2\/posts?tags=1186"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}