{"id":969,"date":"2016-11-29T11:23:07","date_gmt":"2016-11-29T10:23:07","guid":{"rendered":"http:\/\/www.laestaciondeneguri.com\/blog\/?p=969"},"modified":"2016-11-29T11:23:07","modified_gmt":"2016-11-29T10:23:07","slug":"mcenroe-en-el-antzoki","status":"publish","type":"post","link":"http:\/\/www.laestaciondeneguri.com\/blog\/mcenroe-en-el-antzoki\/","title":{"rendered":"MCENROE en el Antzoki"},"content":{"rendered":"<p>Disfrutamos mucho el pasado viernes con MCENROE en el Antzoki (ambientazo y mogoll\u00f3n de caras conocidas, tanto de Getxo como de Bilbao) donde se lucieron versioneando a los grandes cantautores j\u00f3venes de EEUU; tambi\u00e9n lo pasamos fenomenal en casa el s\u00e1bado, o sea, en La Estaci\u00f3n de Neguri con las sentidisimas versiones del repertorio de Graham Nash y de los 70s que hicieron JUAN DUR\u00c1N y PETER ABELS, a los que se sum\u00f3 despu\u00e9s nuestro querido SAM para regalarnos otra media docena de temazos, ya en formato tr\u00edo con Juan y Peter, y a tres voces; se nos escap\u00f3 alguna lagrimilla con unas de Cat Stevens, Simon y Garfunkel y Joni Mitchel, a qu\u00e9 negarlo. Fue la repera, a local lleno, tormenta (agradable) de emoci\u00f3n y de recuerdos.<\/p>\n<p>Hoy recordamos a JASON MOLINA, otro de nuestros h\u00e9roes de la music norteamericana, pero (al igual que Damien Jurado, Bonnie Prince Billy, Mark Kozelek o Kevin Morby), Jason es mucho m\u00e1s de hoy que la cuadrilla homenajeada el s\u00e1bado en La Estaci\u00f3n. Jason Molina naci\u00f3 en 1973, dos a\u00f1os despu\u00e9s de la salida del primer disco en solitario de Nash, por poner una referencia). Lamentablemente, Jason muri\u00f3 hace ya tres a\u00f1os, tras haber cumplido solo cuarenta. Y a\u00fan hoy seguimos lament\u00e1ndolo. Era casi un amigo, de tanto que le quisimos, e incluso tratamos en persona<\/p>\n<p>Aqu\u00ed abajo (esto es un \u00abcompartido\u00bb, je, de nosotros mismos) te proponemos un video de un concierto en 2004 en formato solo; nunca pudimos verle sin grupo, y fue una pena porque nos hubiera encantado; ya es irremediable, no nos quejemos.<\/p>\n<p>Pero si te apetece comprobar c\u00f3mo sonaba en disco y con su banda, haz clik en este enlace de pocas l\u00edneas abajo. Te presentamos, con toda la parca solemnidad que merece, la canci\u00f3n \u00abLioness\u00bb, del disco del mismo nombre -publicado en 2.000-, de Songs :Ohia, primer proyecto colectivo de Jason Molina. De temblar, qu\u00e9 barbaridad, qu\u00e9 preciosidad..<\/p>\n<p><iframe loading=\"lazy\" src=\"https:\/\/www.youtube.com\/embed\/wxAaf16xXRk\" width=\"560\" height=\"315\" frameborder=\"0\" allowfullscreen=\"allowfullscreen\"><\/iframe><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Disfrutamos mucho el pasado viernes con MCENROE en el Antzoki (ambientazo y mogoll\u00f3n de caras conocidas, tanto de Getxo como de Bilbao) donde se lucieron versioneando a los grandes cantautores j\u00f3venes de EEUU; tambi\u00e9n lo pasamos fenomenal en casa el &hellip; <a href=\"http:\/\/www.laestaciondeneguri.com\/blog\/mcenroe-en-el-antzoki\/\">Sigue leyendo <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[18],"tags":[802,662,42,1189,1223,1221,1225,1220,1224,1222],"_links":{"self":[{"href":"http:\/\/www.laestaciondeneguri.com\/blog\/wp-json\/wp\/v2\/posts\/969"}],"collection":[{"href":"http:\/\/www.laestaciondeneguri.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.laestaciondeneguri.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.laestaciondeneguri.com\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/www.laestaciondeneguri.com\/blog\/wp-json\/wp\/v2\/comments?post=969"}],"version-history":[{"count":1,"href":"http:\/\/www.laestaciondeneguri.com\/blog\/wp-json\/wp\/v2\/posts\/969\/revisions"}],"predecessor-version":[{"id":970,"href":"http:\/\/www.laestaciondeneguri.com\/blog\/wp-json\/wp\/v2\/posts\/969\/revisions\/970"}],"wp:attachment":[{"href":"http:\/\/www.laestaciondeneguri.com\/blog\/wp-json\/wp\/v2\/media?parent=969"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.laestaciondeneguri.com\/blog\/wp-json\/wp\/v2\/categories?post=969"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.laestaciondeneguri.com\/blog\/wp-json\/wp\/v2\/tags?post=969"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}