{"id":954,"date":"2016-11-10T09:36:27","date_gmt":"2016-11-10T08:36:27","guid":{"rendered":"http:\/\/www.laestaciondeneguri.com\/blog\/?p=954"},"modified":"2016-11-10T09:36:27","modified_gmt":"2016-11-10T08:36:27","slug":"miercoles-fatidico","status":"publish","type":"post","link":"http:\/\/www.laestaciondeneguri.com\/blog\/miercoles-fatidico\/","title":{"rendered":"Mi\u00e9rcoles fat\u00eddico"},"content":{"rendered":"<p>Hay otro EEUU, bien diferente al de D. Trump y sus admiradores e (incluso, s\u00ed, que no es lo mismo) votantes; un pa\u00eds no tan rancio, no tan tradicionalista, no tan machista, no tan retr\u00f3grado, no tan exclusivista en lo religioso\/espiritual, no tan alejado de lo cient\u00edfico y del progreso social, no tan xen\u00f3fobo, no tan matonista, no tan simplista e inculto, no tan acomplejado y resentido, no tan miedoso y no tan receloso hacia lo nuevo o lo diferente.<\/p>\n<p>Claro que s\u00ed. Hay otro EEUU, el cosmopolita, el de las oportunidades, el de Obama, el de Sanders, el de los descubrimientos cient\u00edficos, el de Tom Waits y Lou Reed, el de Andy Warhol, el de Bob Dylan o Lucinda Wiliams, el del jazz y el blues y el country que tanto nos han inspirado y emocionado, el de las pelis de John Ford, el las reflexiones de Philip Roth, el de Patrti Smith o Bruce Springsteen, el de la contracultura y el antibelicismo, el de las conquistas sociales de gays y lesbianas, el de los dos Woodys (Guthrie y Allen), el de ese Nueva York m\u00e1gico y acogedor, el de las llanuras sin fin y paisajes monumentales y estremecedores, el de ese New Orleans solidario en la cat\u00e1strofe, el de la integraci\u00f3n de razas y culturas, el de los ciudadanos sensibles al deterioro del medio ambiente&#8230;<\/p>\n<p>Siempre ha habido dos pa\u00edses en uno, pero lo cierto es que tambi\u00e9n siempre nos hemos quedado con uno y hemos preferido ignorar al otro, el del Kukuxklan, el del insensato creacionismo, el de la proliferacion de las armas en cada hogar como expresi\u00f3n del la falsa e impostada sensaci\u00f3n de seguridad, y el que discute el cambio clim\u00e1tico, el pa\u00eds ultrarreligioso y fan\u00e1tico tradicionalista, el imperialista y belicista&#8230; pero estaba ah\u00ed, esperando su oportunidad para resurgir. Y se la dieron. Y el monstruo la aprovech\u00f3. \u00bfBuscamos a los culpables?<\/p>\n<p>Cierto, la realidad es m\u00e1s compleja, y en todos lados hay barro, abusos, contradicciones y basura escondida, pero hoy no estamos para matices. S\u00f3lo se nos ocurre una tonter\u00eda, una malicia ir\u00f3nica: Trump y Obama tendr\u00e1n, al fin, algo en com\u00fan, ambos estar\u00e1n sometidos al control de \u00a1los republicanos! Confiamos, por una vez, en ellos, en que paren los pies a este tontolnabo de peli mala,y tiene lo suyo la cosa.<\/p>\n<p>Lo dicho, amamos a ese otro EEUU. Vamos a disfrutar hoy de \u00e9l en el Antzoki bilbaino, en el concierto de blues\/folk\/country de LUKE WINSLOW KING.<\/p>\n<p>Y el pr\u00f3ximo 25 de noviembre haremos lo propio flipando con las versiones que MCENROE har\u00e1n, tambi\u00e9n el en Antzoki, de nuestros adorados Damien Jurado, Johnny Cash, Bill Callahan, Jason Molina, Phosphorescent&#8230;, todos ellos, artistas ciudadanos de ese gran pa\u00eds que sigue siendo EEUU y que seguiremos amando y respetando por mucho que haya decidido que quien lo gobierne sea el papanatas m\u00e1s (aparentemente, al menos) conspicuo, peligroso e inesperado representante de esa otra Am\u00e9rica que tan ajena sentimos.<\/p>\n<p>Cierto es que quiz\u00e1 muchos l\u00edderes dem\u00f3cratas, entre ellos la propia Hillary, merec\u00edan un castigo por asimilarse tan a gusto con las \u00e9lites econ\u00f3micas y sociales y alejarse tanto de las inquietudes y problemas reales de la gente com\u00fan (tomen nota aqu\u00ed tambi\u00e9n algunos politicos nuestros), pero es que el castigo ha sido tan desmesurado&#8230; y sus consecuencias pueder ser tan irreparables&#8230;<\/p>\n<p>Los acontecimientos sociopol\u00edticos m\u00e1s extremos, sorprendentes y radicales, y este lo es a carta cabal, deber\u00edan hacer reflexionar a la gente que vota y a los l\u00edderes que dicen representarles. Porque no todo es lo mismo, claro que no, y porque es la ciudadan\u00eda la que ha decidido libremente en EEUU ayer, y la que en su caso (hay que recordarlo: casi la mitad de la gente no vota, y por algo ser\u00e1) ha preferido quedarse en su casita y no votar siquiera para evitar que sea Trump el presidente, harta de todo y hu\u00e9rfana de l\u00edderes que les hagan sentirse verdaderamente representados. No es un golpe de estado ni nada parecido, es la expresi\u00f3n de la opini\u00f3n de los ciudadanos que deciden votar, que es la que cuenta. Hay que asumirlo, la democracia tiene estas cosas. Mal que nos pese.<\/p>\n<p>\u00abEs la cultura, est\u00fapidos\u00bb, tambi\u00e9n cabr\u00eda decir, \u00bfno? Porque para votar al machista, xen\u00f3fobo, par\u00f3dico, histri\u00f3n y retr\u00f3grado Trump hay que ser un inculto\/ignorante de manual (y algo tendr\u00e1n que ver en esto las pol\u00edticas educativas, el consumo desaforado de cierta televisi\u00f3n y prensa, el machismo rampante, el consumismo como \u00fanico medio propuesto para hallar la felicidad&#8230;), o un carcamal reaccionario de mucho cuidado, que de todo tiene que haber y siempre habr\u00e1, o un desenga\u00f1ado de todo que vota con resentimiento y m\u00e1s en contra del sistema que a favor de nada, o un c\u00ednico que prefiere aupar a la presidencia a un loco narcisista imprevisible, ca\u00f3tico y sin experiencia alguna en la pol\u00edtica, y sentarse ante la tele cada d\u00eda para divertirse con sus ocurrencias aunque lleven a su pa\u00eds al desastre.<\/p>\n<p>El Breixit, el auge de los nacionalismos xen\u00f3fobos en Europa, la impostura europea con los refugiados sirios y en general con los emigrantes, la crisis econ\u00f3mica y financiera que en Espa\u00f1a la han pagado y la siguen pagando sobre todo las clases medias y bajas&#8230; y ahora Trump en la presidencia de EEUU, son la manifestaci\u00f3n de un mismo hecho, de una regresi\u00f3n, de un paso atr\u00e1s en la evoluci\u00f3n sociopol\u00edtica, al que hay que hacer frente, con decisi\u00f3n y pedagog\u00eda democr\u00e1tica y con m\u00e1s cultura y m\u00e1s arte de los que ennoblecen al individuo y lo integran en el grupo, en un grupo cada vez mayor que debe convertirse al final en el total de la humanidad. Qu\u00e9 intensos nos ponemos&#8230;<\/p>\n<p>La verdad es que pensamos que, ante todo, Trump es un narcisista eg\u00f3latra que ha conseguido la meta so\u00f1ada y m\u00e1s dif\u00edcil para un norteamericano, un objetivo casi imposible de conseguir incluso para los m\u00e1s dotados y, por ello, a la altura de su megaloman\u00eda y su insaciable vanidad. Y que Trump ha jugado el papel histri\u00f3nico de agitador de masas irreverente y cargado de rabia, desafio anti-sistema y humor socarr\u00f3n; es decir, el papel de comedia y espect\u00e1culo que le conven\u00eda para llegar, impactar, seducir, hacer re\u00edr y convencer a la gente menos cultivada y m\u00e1s resentida, pero cuando las cosas se ponen serias, tras el triunfo electoral y con todos los l\u00edderes del mundo tomando nota de sus primeras declaraciones como presidente de EEUU, se olvida de las patochadas y mentiras con que embarr\u00f3 la campa\u00f1a y hace un t\u00edpico discurso de normalidad institucional y sensatez de gran jefe de la barraca. Quien haya escuchado (nosotros lo hemos hecho en directo a eso de las 9 am hora espa\u00f1ola) el discurso de la victoria de Trump sabe a lo que nos referimos: le hemos visto en plan integrador, \u00abagradecido\u00bb (s\u00ed, s\u00ed) al \u00abgran esfuerzo\u00bb de Hillary por su pa\u00eds, conciliador con la minor\u00ecas e incluso con con quienes no le han votado, en fin&#8230; una cosa apa\u00f1ada, del todo com\u00fan y corriente, y muy distinto a la parodia de grotesco fantoche que hemos visto en campa\u00f1a.<\/p>\n<p>Venga, vamos a dejarlo que si no, nos calentamos hasta el incendio.<\/p>\n<p>Un pajarito nos ha contado que una de las versiones que har\u00e1n MCENROE en el ciclo Izar&amp;Star ser\u00e1 la de esta fant\u00e1stica canci\u00f3n de Damien Jurado, uno de nuestros cantautorores favoritos de EEUU (es de Seattle) y del mundo mundial:<\/p>\n<p><iframe loading=\"lazy\" src=\"https:\/\/www.youtube.com\/embed\/Y1t6m0WruMQ?list=PLUUaq4jnSm_UfbJSkMVES5ZQzKIxkI9pX\" width=\"560\" height=\"315\" frameborder=\"0\" allowfullscreen=\"allowfullscreen\"><\/iframe><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Hay otro EEUU, bien diferente al de D. Trump y sus admiradores e (incluso, s\u00ed, que no es lo mismo) votantes; un pa\u00eds no tan rancio, no tan tradicionalista, no tan machista, no tan retr\u00f3grado, no tan exclusivista en lo &hellip; <a href=\"http:\/\/www.laestaciondeneguri.com\/blog\/miercoles-fatidico\/\">Sigue leyendo <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[1],"tags":[1188,42,1193,1189,979,1190,644,1192,605,1191],"_links":{"self":[{"href":"http:\/\/www.laestaciondeneguri.com\/blog\/wp-json\/wp\/v2\/posts\/954"}],"collection":[{"href":"http:\/\/www.laestaciondeneguri.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.laestaciondeneguri.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.laestaciondeneguri.com\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/www.laestaciondeneguri.com\/blog\/wp-json\/wp\/v2\/comments?post=954"}],"version-history":[{"count":1,"href":"http:\/\/www.laestaciondeneguri.com\/blog\/wp-json\/wp\/v2\/posts\/954\/revisions"}],"predecessor-version":[{"id":955,"href":"http:\/\/www.laestaciondeneguri.com\/blog\/wp-json\/wp\/v2\/posts\/954\/revisions\/955"}],"wp:attachment":[{"href":"http:\/\/www.laestaciondeneguri.com\/blog\/wp-json\/wp\/v2\/media?parent=954"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.laestaciondeneguri.com\/blog\/wp-json\/wp\/v2\/categories?post=954"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.laestaciondeneguri.com\/blog\/wp-json\/wp\/v2\/tags?post=954"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}