{"id":917,"date":"2016-10-05T08:34:03","date_gmt":"2016-10-05T07:34:03","guid":{"rendered":"http:\/\/www.laestaciondeneguri.com\/blog\/?p=917"},"modified":"2016-10-05T08:34:47","modified_gmt":"2016-10-05T07:34:47","slug":"espacios-de-serenidad-a-traves-de-la-musica","status":"publish","type":"post","link":"http:\/\/www.laestaciondeneguri.com\/blog\/espacios-de-serenidad-a-traves-de-la-musica\/","title":{"rendered":"Espacios de serenidad a trav\u00e9s de la m\u00fasica"},"content":{"rendered":"<p>MI\u00c9RCOLES, pese a la excitaci\u00f3n ante la inminencia del concierto de nuestro querid\u00edsimo PETER BRUNTNELL (Colegio de Abogados en Bilbao, entrada libre, a las 8 pm), paradigma del artista de culto que deber\u00eda llegar a mucha m\u00e1s gente por la calidad de su music, por la pegada del intimismo evocador y melanc\u00f3lico pero en cierta medida animado de sus canciones pop-rock con solera folk, sentimos que necesitamos con apremio, incluso tan de buena ma\u00f1ana crear un espacio -siquiera sonoro- sereno, dominado por la calma, el sosiego, la tranquilidad&#8230; para trabajar un poco, para vivir, en definitiva.<\/p>\n<p>Y no es porque hayamos leido en el peri\u00f3dico, por ejemplo, que ahora el PP, manchado esta semana por el juicio de la Gurtel, dice que no le basta con una abstenci\u00f3n del PSOE, que quiere un acuerdo que comprometa m\u00e1s al partido en v\u00edas de extinci\u00f3n, pero tampoco nos escandalicemos ante este cambio de planteamiento. Aqu\u00ed nos tragamos todo, y la sentencia es aplicable a todo lo ancho del espector pol\u00edtico. Al tema: empieza a sentir el PP el v\u00e9rtigo, el miedo de enfrentarse cada d\u00eda de la (a\u00fan no nacida) pr\u00f3xima legislatura a una oposici\u00f3n beligerante\/vengativa que le impida gobernar; adem\u00e1s, hecho decisivo, la perspectiva de unas terceras elecciones no le aterra tanto como al resto de partidos: piensa -lo dicen las encuestas- que puede mejorar sus resultados y ampliar el n\u00famero de diputados. Podr\u00edamos preguntarnos por qu\u00e9 hace unas semanas no solo le bastaba al PP la abstenci\u00f3n, sino que casi llegaba a exig\u00edrsele a aquel PSOE a\u00fan no tan demolido como lo est\u00e1 hoy. Las cosas cambian, claro. Para todos. Que se lo pregunten a Iglesias o a Rivera, las j\u00f3venes promesas de anteayer, aquellos tallos verdes de hace a\u00fan pocos a\u00f1os que se nos antojan hoy resabiados y vetustos \u00e1rboles del contaminado paisaje de la pol\u00edtica espa\u00f1ola.<\/p>\n<p>Necesitamos, dec\u00edamos, hoy y tantos otros d\u00edas, una sobredosis de equilibrio y templanza, crear un espacio sereno para trabajar, para poder sentir, para vivir, en definitiva. Y hay m\u00fasicas que nos ayudan a llegar a ese espacio, impregn\u00e1ndolo adem\u00e1s de belleza y serenidad. Como las que contiene \u00abOrph\u00e9e\u00bb el nuevo y emocionante disco del finland\u00e9s JOHANN JOHANNSSON. El video hace justicia a \u2018Flight from the City\u2019, la canci\u00f3n que abre este m\u00e1s que recomendable disco de music neocl\u00e1sica, que remiute al ambient, al minimalismo, a las bso de las pelis (de las que JJ es un experto y prestigioso creador, de hecho, le han pedido que haga la banda sonora de la secuela de \u00abBlade Runner\u00bb) y un poco, por qu\u00e9 no decirlo, a aquella new age de la que ya nadie quiere acordarse.<\/p>\n<p>Nos vemos en el Colegio, esta tarde. De Abogados, s\u00ed, en Bilbao. Peter Brutnell y sud delicadas canciones nos esperan.<\/p>\n<p>De momento, mientras hacemos tiempo y seguimos trabajando (hoy toca hacer las cuentas y cerrar trimestre), nos dejamos invadir por la serena belleza de la music de JOHANN JOHANNSSON<\/p>\n<p><iframe loading=\"lazy\" width=\"560\" height=\"315\" src=\"https:\/\/www.youtube.com\/embed\/AlftMNmDH00\" frameborder=\"0\" allowfullscreen><\/iframe><\/p>\n","protected":false},"excerpt":{"rendered":"<p>MI\u00c9RCOLES, pese a la excitaci\u00f3n ante la inminencia del concierto de nuestro querid\u00edsimo PETER BRUNTNELL (Colegio de Abogados en Bilbao, entrada libre, a las 8 pm), paradigma del artista de culto que deber\u00eda llegar a mucha m\u00e1s gente por la &hellip; <a href=\"http:\/\/www.laestaciondeneguri.com\/blog\/espacios-de-serenidad-a-traves-de-la-musica\/\">Sigue leyendo <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[1],"tags":[],"_links":{"self":[{"href":"http:\/\/www.laestaciondeneguri.com\/blog\/wp-json\/wp\/v2\/posts\/917"}],"collection":[{"href":"http:\/\/www.laestaciondeneguri.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.laestaciondeneguri.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.laestaciondeneguri.com\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/www.laestaciondeneguri.com\/blog\/wp-json\/wp\/v2\/comments?post=917"}],"version-history":[{"count":1,"href":"http:\/\/www.laestaciondeneguri.com\/blog\/wp-json\/wp\/v2\/posts\/917\/revisions"}],"predecessor-version":[{"id":918,"href":"http:\/\/www.laestaciondeneguri.com\/blog\/wp-json\/wp\/v2\/posts\/917\/revisions\/918"}],"wp:attachment":[{"href":"http:\/\/www.laestaciondeneguri.com\/blog\/wp-json\/wp\/v2\/media?parent=917"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.laestaciondeneguri.com\/blog\/wp-json\/wp\/v2\/categories?post=917"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.laestaciondeneguri.com\/blog\/wp-json\/wp\/v2\/tags?post=917"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}