{"id":893,"date":"2016-09-22T12:19:03","date_gmt":"2016-09-22T11:19:03","guid":{"rendered":"http:\/\/www.laestaciondeneguri.com\/blog\/?p=893"},"modified":"2016-09-22T12:19:03","modified_gmt":"2016-09-22T11:19:03","slug":"jueves-fluye-setiembre-y-estamos-contentos","status":"publish","type":"post","link":"http:\/\/www.laestaciondeneguri.com\/blog\/jueves-fluye-setiembre-y-estamos-contentos\/","title":{"rendered":"JUEVES, fluye setiembre y ESTAMOS CONTENTOS"},"content":{"rendered":"<p>Nueva canci\u00f3n de Ricardo MCENROE.<br \/>\nAyer disfrutamos de un d\u00eda espl\u00e9ndido y por la noche gan\u00f3 nuevamente un ATHLETIC que no termina de funcionar pero va sobrado de eficiencia y est\u00e1 ya a solo dos puntos del segundo clasificado en la Liga; adem\u00e1s, LAS OBRAS ENFRENTE de tu local favorito de Getxo van finalizando y confiamos en que en menos de un par de semanas tengamos la zona impecablemente urbanizada, con su nuevo parquecito con bancos y con sus flamantes plazas de aparcamiento en el otro lado de la carretera. Nos referimos, claro est\u00e1, a la zona que vemos enfrente y a los lados de La Estaci\u00f3n de Neguri, porque el despliegue para la construcci\u00f3n de los bloques de viviendas que ir\u00e1n en la parte superior de la Avenida de Neguri, que sepamos, a\u00fan no tiene siquiera plazos. Adem\u00e1s, estas obras -pensamos- no nos afectar\u00e1n tanto como las de iniciativa municipal que llevamos sufriendo desde hace m\u00e1s de cuatro meses justo delante de nuestra terraza.<\/p>\n<p>De POL\u00cdTICA, ni una palabra, ninguna. Hartos.<\/p>\n<p>Tambi\u00e9n fluye hoy la sonrisa porque este finde vamos a desplazarnos hasta DONOSTI a ver pelis y a disfrutar, acompa\u00f1ados de espl\u00e9ndidos amigos que nos hospedan en su casa, del estupendo y despreocupado ambiente (se siente: vinitos, pintxos cotilleando sobre el artista que tienes al lado en el bar, deliciosos y brumosos paseos, interminables desayunos leyendo la prensa, ver a Carlos Boyero con su sempiterna cara de aburrido de todo sentado en un banco como pensando en cualquier tema sin inter\u00e9s, garbeo somnoliento por las tiendas\u2026) que reina en la ciudad mientras dura el festival. Por si hay curiosidad, deciros las que, tras dura deliberaci\u00f3n con nosotros mismos, hemos decidido ver estas cinco: dos de la secci\u00f3n oficial a concurso (\u201cAmerican Pastoral\u201d y \u201cEl invierno\u201d) y tres de Perlas (\u201cFuocoammare\u201d, \u201cFrantz\u201d y \u201cSieranevada\u201d). No nos extenderemos sobre cada peli, pero estamos satisfechos porque pudimos comprar entradas para las pelis ( y las sesiones) que hab\u00edamos puesto en primer lugar de todas las que hab\u00eda en cartelera para viernes y s\u00e1bado; es decir, mejor imposible. Escudri\u00f1amos una a una todas las que hab\u00eda, y elegimos tranquilamente.Tres horas de entretenida tarea para una ma\u00f1ana del domingo (ejem, de seis y media a nueve y media). Otra cosa es que hayamos acertado, pero lo bueno es que vamos a poder ver las que m\u00e1s nos llamaron la atenci\u00f3n, por el tema, el director, los actores\u2026 Los m\u00e1s cin\u00e9filos, efectivamente, podr\u00e1n pensar, y acertar\u00e1n, que hemos pecado de convencionales y de amarrateguis, pero es que hemos preferido tirar por pelis de inter\u00e9s y calidad casi asegurada (la latina, \u201cEl invierno\u201d, es quiz\u00e1 la \u00fanica de riesgo), ser\u00e1 que nos vamos haciendo mayores. La verdad es que hemos podido comprar entradas para las pelis que hab\u00edamos puesto en primer lugar de todas las que hab\u00eda en cartelera para viernes y s\u00e1bado; es decir, mejor imposible.<\/p>\n<p>Tambi\u00e9n nos alegra tener en agenda un concierto que presumimos espl\u00e9ndido, el del cantautor pop-rock brit\u00e1nico PETER BRUNTNELL. Anoten: mi\u00e9rcoles, 5 de octubre, Colegio Abogados, Bilbao. Volveremos al asunto, que merece la pena. No tenemos para olvidar el concierto que le vimos hace un a\u00f1o o as\u00ed en el Antzoki, y adem\u00e1s esta vez viene con banda. Imprescindible. Si vienes mucho a La Estaci\u00f3n, te tiene que sonar: pinchamos a todas horas las cancionazas del nuevo disco de PETER BRUNTNELL.<\/p>\n<p>Por \u00faltimo, tambi\u00e9n estamos contentos hoy porque ya podemos escuchar no una sino dos canciones de \u201cLluvia y Truenos\u201d, disco que han grabado a medias RICARDO MCENROE y el reconocido m\u00fasico pop barcelon\u00e9s THE NEW RAEMON y que se publica el 11 de Noviembre.<\/p>\n<p>Tanto \u201cGracia\u201d, de Ricardo Mcenroe, como \u201cMonta\u00f1as\u201d, de The New Raemon suenan fenomenal, pero cada uno tiene sus debilidades, y la nuestra est\u00e1 clara. Hay cosas que no se explican.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Nueva canci\u00f3n de Ricardo MCENROE. Ayer disfrutamos de un d\u00eda espl\u00e9ndido y por la noche gan\u00f3 nuevamente un ATHLETIC que no termina de funcionar pero va sobrado de eficiencia y est\u00e1 ya a solo dos puntos del segundo clasificado en &hellip; <a href=\"http:\/\/www.laestaciondeneguri.com\/blog\/jueves-fluye-setiembre-y-estamos-contentos\/\">Sigue leyendo <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[1],"tags":[],"_links":{"self":[{"href":"http:\/\/www.laestaciondeneguri.com\/blog\/wp-json\/wp\/v2\/posts\/893"}],"collection":[{"href":"http:\/\/www.laestaciondeneguri.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.laestaciondeneguri.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.laestaciondeneguri.com\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/www.laestaciondeneguri.com\/blog\/wp-json\/wp\/v2\/comments?post=893"}],"version-history":[{"count":1,"href":"http:\/\/www.laestaciondeneguri.com\/blog\/wp-json\/wp\/v2\/posts\/893\/revisions"}],"predecessor-version":[{"id":894,"href":"http:\/\/www.laestaciondeneguri.com\/blog\/wp-json\/wp\/v2\/posts\/893\/revisions\/894"}],"wp:attachment":[{"href":"http:\/\/www.laestaciondeneguri.com\/blog\/wp-json\/wp\/v2\/media?parent=893"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.laestaciondeneguri.com\/blog\/wp-json\/wp\/v2\/categories?post=893"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.laestaciondeneguri.com\/blog\/wp-json\/wp\/v2\/tags?post=893"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}