{"id":843,"date":"2016-05-11T09:04:47","date_gmt":"2016-05-11T08:04:47","guid":{"rendered":"http:\/\/www.laestaciondeneguri.com\/blog\/?p=843"},"modified":"2016-05-11T09:04:47","modified_gmt":"2016-05-11T08:04:47","slug":"paisaje-prenocturno","status":"publish","type":"post","link":"http:\/\/www.laestaciondeneguri.com\/blog\/paisaje-prenocturno\/","title":{"rendered":"Paisaje prenocturno"},"content":{"rendered":"<p>Arena removida en la playa convertida en colinas que modifican el paisaje de un solitario Ereaga prenocturno. Foto tomada el pasado lunes, tomando un refresco en el chiringuito mientras languidec\u00eda la tarde.<\/p>\n<p>Un par de Ricardos sentados e inopinadamente cansados tras tan breve paseo, charlando y disfrutando de esos momentos que, sin que pase nada especial m\u00e1s all\u00e1 de la soledad compartida y de un bello y silencioso paisaje, son candidatos a piezas de recuerdo.<\/p>\n<p><a href=\"http:\/\/www.laestaciondeneguri.com\/blog\/wp-content\/uploads\/2016\/05\/CB_mayo16.jpg\" rel=\"attachment wp-att-844\"><img decoding=\"async\" loading=\"lazy\" class=\"alignnone size-medium wp-image-844\" src=\"http:\/\/www.laestaciondeneguri.com\/blog\/wp-content\/uploads\/2016\/05\/CB_mayo16-300x101.jpg\" alt=\"CB_mayo16\" width=\"300\" height=\"101\" srcset=\"http:\/\/www.laestaciondeneguri.com\/blog\/wp-content\/uploads\/2016\/05\/CB_mayo16-300x101.jpg 300w, http:\/\/www.laestaciondeneguri.com\/blog\/wp-content\/uploads\/2016\/05\/CB_mayo16-768x260.jpg 768w, http:\/\/www.laestaciondeneguri.com\/blog\/wp-content\/uploads\/2016\/05\/CB_mayo16-500x169.jpg 500w, http:\/\/www.laestaciondeneguri.com\/blog\/wp-content\/uploads\/2016\/05\/CB_mayo16.jpg 920w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Arena removida en la playa convertida en colinas que modifican el paisaje de un solitario Ereaga prenocturno. Foto tomada el pasado lunes, tomando un refresco en el chiringuito mientras languidec\u00eda la tarde. Un par de Ricardos sentados e inopinadamente cansados &hellip; <a href=\"http:\/\/www.laestaciondeneguri.com\/blog\/paisaje-prenocturno\/\">Sigue leyendo <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[1],"tags":[],"_links":{"self":[{"href":"http:\/\/www.laestaciondeneguri.com\/blog\/wp-json\/wp\/v2\/posts\/843"}],"collection":[{"href":"http:\/\/www.laestaciondeneguri.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.laestaciondeneguri.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.laestaciondeneguri.com\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/www.laestaciondeneguri.com\/blog\/wp-json\/wp\/v2\/comments?post=843"}],"version-history":[{"count":1,"href":"http:\/\/www.laestaciondeneguri.com\/blog\/wp-json\/wp\/v2\/posts\/843\/revisions"}],"predecessor-version":[{"id":845,"href":"http:\/\/www.laestaciondeneguri.com\/blog\/wp-json\/wp\/v2\/posts\/843\/revisions\/845"}],"wp:attachment":[{"href":"http:\/\/www.laestaciondeneguri.com\/blog\/wp-json\/wp\/v2\/media?parent=843"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.laestaciondeneguri.com\/blog\/wp-json\/wp\/v2\/categories?post=843"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.laestaciondeneguri.com\/blog\/wp-json\/wp\/v2\/tags?post=843"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}