{"id":839,"date":"2016-04-26T14:46:13","date_gmt":"2016-04-26T13:46:13","guid":{"rendered":"http:\/\/www.laestaciondeneguri.com\/blog\/?p=839"},"modified":"2016-04-26T15:01:12","modified_gmt":"2016-04-26T14:01:12","slug":"las-obras-enfrente-de-la-estacion","status":"publish","type":"post","link":"http:\/\/www.laestaciondeneguri.com\/blog\/las-obras-enfrente-de-la-estacion\/","title":{"rendered":"Las obras enfrente de La Estaci\u00f3n"},"content":{"rendered":"<p>Os queremos hablar\u00a0 de LAS OBRAS ENFRENTE de La Estaci\u00f3n, cuya (agradable) plasmaci\u00f3n hasta el momento era el desbrozo de \u00e1rboles, arbustos y vegetaci\u00f3n varia de la finca situada justo enfrente de nuestro local y que se prolonga a lo largo de toda la Avda. Neguri, por un lado y de la c\/ San Ignacio por otro. Llevan una semana y en pocos d\u00edas terminan. Ganamos (todos) en luz y en vistas, perfecto.Habr\u00e1 que ver cu\u00e1l es la siguiente fase del proyecto. Especulaciones, todas, pero no estamos nosotros para alimentarlas, claro que no.<\/p>\n<p>Os trasmitimos la info de que disponemos y nos parece fiable:<br \/>\nSabemos (y de momento, no opinamos) que:<\/p>\n<p>1) ma\u00f1ana, mi\u00e9rcoles 27, se proceder\u00e1 a la tala de los pl\u00e1tanos de la calle San Ignacio. Objetivo: anchar la carretera y que haya un poco m\u00e1s de espacio para circular y para aparcar en esa estrech\u00edsima calle<\/p>\n<p>2) el muro de varios metros de altura que \u00absoporta\u00bb la enorme finca que linda con la totalidad del discurrir de Avenida Neguri se derrumbar\u00e1 en breve y se mover\u00e1 tres o cuatro metros hacia atr\u00e1s. Este nuevo espacio permitir\u00e1 Avenida Neguri ofrezca APARCAMIENTO a ambos lados de la calzada. Seguir\u00e1<br \/>\nsiendo, eso s\u00ed, de un solo sentido de circulaci\u00f3n, el opuesto al de la c\/ San Ignacio.<\/p>\n<p>3) est\u00e1n previstas dos edificaciones distintas en el amplio solar, pero nada se sabe de fechas de inicio de las obras de construcci\u00f3n.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Os queremos hablar\u00a0 de LAS OBRAS ENFRENTE de La Estaci\u00f3n, cuya (agradable) plasmaci\u00f3n hasta el momento era el desbrozo de \u00e1rboles, arbustos y vegetaci\u00f3n varia de la finca situada justo enfrente de nuestro local y que se prolonga a lo &hellip; <a href=\"http:\/\/www.laestaciondeneguri.com\/blog\/las-obras-enfrente-de-la-estacion\/\">Sigue leyendo <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[887],"tags":[1077,1078,138],"_links":{"self":[{"href":"http:\/\/www.laestaciondeneguri.com\/blog\/wp-json\/wp\/v2\/posts\/839"}],"collection":[{"href":"http:\/\/www.laestaciondeneguri.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.laestaciondeneguri.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.laestaciondeneguri.com\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/www.laestaciondeneguri.com\/blog\/wp-json\/wp\/v2\/comments?post=839"}],"version-history":[{"count":2,"href":"http:\/\/www.laestaciondeneguri.com\/blog\/wp-json\/wp\/v2\/posts\/839\/revisions"}],"predecessor-version":[{"id":841,"href":"http:\/\/www.laestaciondeneguri.com\/blog\/wp-json\/wp\/v2\/posts\/839\/revisions\/841"}],"wp:attachment":[{"href":"http:\/\/www.laestaciondeneguri.com\/blog\/wp-json\/wp\/v2\/media?parent=839"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.laestaciondeneguri.com\/blog\/wp-json\/wp\/v2\/categories?post=839"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.laestaciondeneguri.com\/blog\/wp-json\/wp\/v2\/tags?post=839"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}