{"id":829,"date":"2016-04-20T09:49:04","date_gmt":"2016-04-20T08:49:04","guid":{"rendered":"http:\/\/www.laestaciondeneguri.com\/blog\/?p=829"},"modified":"2016-04-20T09:51:22","modified_gmt":"2016-04-20T08:51:22","slug":"que-se-nos-viene-encima-el-agua-cuidado","status":"publish","type":"post","link":"http:\/\/www.laestaciondeneguri.com\/blog\/que-se-nos-viene-encima-el-agua-cuidado\/","title":{"rendered":"\u00a1Que se nos viene encima el agua, cuidado!"},"content":{"rendered":"<p>\u00a1Que se nos viene encima el agua, cuidado!<br \/>\nD\u00f3nde hay que hacer la rogatoria, por favor. \u00a1Necesitamos luz, queremos ver el sol, convencernos de que el tiempo no es nuestro enemigo declarado! Pero necesitamos pruebas de peso. Un cambio brusco, por ejemplo: ma\u00f1ana, sol. Pero va a ser que no. El pron\u00f3stico indica lluvia y nubes durante \u00a1seis d\u00edas! m\u00e1s.<\/p>\n<p>Banda sonora de los estadounidenses RICHMOND FONTAINE, \u00abWhitey and Me \u00abuna pieza impresionante de su nuevo disco. Alt-country\/songwritter del que nos gusta. Cadencioso y suave, s\u00ed, pero contundente y directo al centro.<br \/>\n<iframe loading=\"lazy\" src=\"https:\/\/www.youtube.com\/embed\/MBSOAkApFpQ\" width=\"560\" height=\"315\" frameborder=\"0\" allowfullscreen=\"allowfullscreen\"><\/iframe><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00a1Que se nos viene encima el agua, cuidado! D\u00f3nde hay que hacer la rogatoria, por favor. \u00a1Necesitamos luz, queremos ver el sol, convencernos de que el tiempo no es nuestro enemigo declarado! Pero necesitamos pruebas de peso. Un cambio brusco, &hellip; <a href=\"http:\/\/www.laestaciondeneguri.com\/blog\/que-se-nos-viene-encima-el-agua-cuidado\/\">Sigue leyendo <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[98,887],"tags":[1070,1044],"_links":{"self":[{"href":"http:\/\/www.laestaciondeneguri.com\/blog\/wp-json\/wp\/v2\/posts\/829"}],"collection":[{"href":"http:\/\/www.laestaciondeneguri.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.laestaciondeneguri.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.laestaciondeneguri.com\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/www.laestaciondeneguri.com\/blog\/wp-json\/wp\/v2\/comments?post=829"}],"version-history":[{"count":2,"href":"http:\/\/www.laestaciondeneguri.com\/blog\/wp-json\/wp\/v2\/posts\/829\/revisions"}],"predecessor-version":[{"id":831,"href":"http:\/\/www.laestaciondeneguri.com\/blog\/wp-json\/wp\/v2\/posts\/829\/revisions\/831"}],"wp:attachment":[{"href":"http:\/\/www.laestaciondeneguri.com\/blog\/wp-json\/wp\/v2\/media?parent=829"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.laestaciondeneguri.com\/blog\/wp-json\/wp\/v2\/categories?post=829"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.laestaciondeneguri.com\/blog\/wp-json\/wp\/v2\/tags?post=829"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}