{"id":762,"date":"2016-03-07T09:57:03","date_gmt":"2016-03-07T08:57:03","guid":{"rendered":"http:\/\/www.laestaciondeneguri.com\/blog\/?p=762"},"modified":"2016-03-21T09:28:00","modified_gmt":"2016-03-21T08:28:00","slug":"oferta-musical-a-raudales","status":"publish","type":"post","link":"http:\/\/www.laestaciondeneguri.com\/blog\/oferta-musical-a-raudales\/","title":{"rendered":"M\u00fasica en directo a raudales"},"content":{"rendered":"<p>ESTO DE LA AFICI\u00d3N (desmedida) por la m\u00fasica en directo es poco menos que un sinvivir. Hablamos de los nervios relacionados con la log\u00edstica y el gasto, m\u00e1s que nada.<br \/>\nConseguir las entradas, decidirse entre las opciones posibles (m\u00e1s o menso caras, m\u00e1s o menos cerca&#8230;) , ver la disponibilidad de las fechas y, lo peor, hacer el dispendio.<\/p>\n<p>ESTA NOCHE, por ejemplo, (05\/03\/2016),\u00a0 asistiremos al espectacular homenaje que hasta cinco bandas vascas (12 euros, adelantada, sale la broma, que tampoco es \u00eddem), varias de ellas muy renombradas, van a rendir al reci\u00e8n fallecido DAVID BOWIE en el Antzoki bilbaino dentro del cliclo IZAR &amp; STAR, pero nos hemos levantado hoy s\u00e1bado muy pronto, para variar, y un poco estresados.<\/p>\n<p>No para de llover, hace un tiempo tan horroroso que no se puede casi ni sacar al perro a pasear. Y, adem\u00e1s, nos ponen nerviosos ciertas tesituras: que si comprar el abono del BBK Live (est\u00e1 decidido que vamos, el cartel lo exige, y por si faltaba algo han incorporado a los canadienses Junior Boys, techno-pop delicado y con sentimiento), que si recapacitar si merece la pena gastar tanto por ver a Bruce, a pesar de que venga con la gira del m\u00edtico disco The River (\u00bfDonosti, en martes, o Madrid, en domingo? o a The Cure en el BEC\u2026<\/p>\n<p>Y como nos gusta casi todo, un anuncio de hoy en el diario nos ha recordado algo que le\u00edmos hace pocos d\u00edas: hay OTRO GRAN EVENTO MUSICAL, en este caso de cl\u00e1sica y de nivel mundial, je, que no nos gustar\u00eda perdernos. Se ha dado en llamar Ciclo de Grandes Conciertos BILBAO PUERTO DE ARTE. Consiste en un ciclo de seis citas alucinantes, la primera el 16 de setiembre de este a\u00f1o y la \u00faltima el 30 de abril de 2.017. Largo me lo f\u00edas, pero&#8230;. Dos nombres para hacernos una idea de d\u00f3nde nos estamos moviendo: el director de orquesta ZUBIN METHA , que abre el ciclo con la Orquesta del Mayo Florentino, y el pianista IVO POGORELICH, que lo cierra con la Orquesta de Munich. El abono para los seis conciertos cuesta desde 152 hasta 385 euros, oneroso, s\u00ed, pero m\u00e1s que razonable precio teniendo en cuenta la calidad y prestigio universal de los artistas. De momento, solo est\u00e1n a la venta los abonos. Al menos, ning\u00fan concierto toca en laborable salvo el del 7 de diciembre que es puente.<\/p>\n<p>\u00bfQu\u00e9 hacer? \u00bfComprar el abono ahora que &#8211; lo hemos comprobado- a\u00fan hay muy buenas butacas disponibles, por ejemplo, en la fila 10 centradas del Euskalduna?<\/p>\n<p>Llevamos desde que ha clareado el d\u00eda escuchando cl\u00e1sica, nos ha dado por ah\u00ed, y uno de los momentos m\u00e1s placenteros ha sido reencontrarnos con una de las piezas m\u00e1s populares de la m\u00fasica cl\u00e1sica, \u00abViolin Concerto A minor\u00bb de J. S. Bach , interpretada (el video corresponde a un concierto de 1991, precisamente en nuestro pa\u00eds) por los Virtuosos de Mosc\u00fa y con el entonces virtuoso violinista y hoy tambi\u00e9n director de orquesta Vlad\u00edmir Spivakov. No somos en absoluto entendidos en cl\u00e1sica, pero por Dios, como suenan\u2026<\/p>\n<p>Pues bien, dentro de ese ciclo del que os hablamos, concretamente en el concierto que har\u00e1 el n\u00famero dos de la serie de seis, figura otra de las fechas clave (23 octubre): VLADIMIR SPIVAKOV tocando el viol\u00edn y dirigiendo a los Virtuosos de Mosc\u00fa, como en el video hace 25 a\u00f1os.<\/p>\n<p>Lo dicho, os dejamos con Bach y con Spivakov, que confiamos animen esta lluviosa y fr\u00eda ma\u00f1ana de s\u00e1bado. Seguro que la ennoblecen y engrandecen, que es lo que hace el arte cuando lo es de verdad.<\/p>\n<p><iframe loading=\"lazy\" src=\"https:\/\/www.youtube.com\/embed\/T1nvxrCLzOQ\" width=\"420\" height=\"315\" frameborder=\"0\" allowfullscreen=\"allowfullscreen\"><\/iframe><\/p>\n","protected":false},"excerpt":{"rendered":"<p>ESTO DE LA AFICI\u00d3N (desmedida) por la m\u00fasica en directo es poco menos que un sinvivir. Hablamos de los nervios relacionados con la log\u00edstica y el gasto, m\u00e1s que nada. Conseguir las entradas, decidirse entre las opciones posibles (m\u00e1s o &hellip; <a href=\"http:\/\/www.laestaciondeneguri.com\/blog\/oferta-musical-a-raudales\/\">Sigue leyendo <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[1],"tags":[956,957,946,958,955,960,959,961,962],"_links":{"self":[{"href":"http:\/\/www.laestaciondeneguri.com\/blog\/wp-json\/wp\/v2\/posts\/762"}],"collection":[{"href":"http:\/\/www.laestaciondeneguri.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.laestaciondeneguri.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.laestaciondeneguri.com\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/www.laestaciondeneguri.com\/blog\/wp-json\/wp\/v2\/comments?post=762"}],"version-history":[{"count":3,"href":"http:\/\/www.laestaciondeneguri.com\/blog\/wp-json\/wp\/v2\/posts\/762\/revisions"}],"predecessor-version":[{"id":765,"href":"http:\/\/www.laestaciondeneguri.com\/blog\/wp-json\/wp\/v2\/posts\/762\/revisions\/765"}],"wp:attachment":[{"href":"http:\/\/www.laestaciondeneguri.com\/blog\/wp-json\/wp\/v2\/media?parent=762"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.laestaciondeneguri.com\/blog\/wp-json\/wp\/v2\/categories?post=762"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.laestaciondeneguri.com\/blog\/wp-json\/wp\/v2\/tags?post=762"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}