{"id":497,"date":"2014-12-24T11:51:28","date_gmt":"2014-12-24T10:51:28","guid":{"rendered":"http:\/\/www.laestaciondeneguri.com\/blog\/?p=497"},"modified":"2014-12-24T11:53:31","modified_gmt":"2014-12-24T10:53:31","slug":"desde-la-estacion-felices-fiestas","status":"publish","type":"post","link":"http:\/\/www.laestaciondeneguri.com\/blog\/desde-la-estacion-felices-fiestas\/","title":{"rendered":"Desde La Estaci\u00f3n: !felices fiestas!"},"content":{"rendered":"<p>VIERNES 24 DE DICIEMBRE, EL D\u00cdA DE NOCHEBUENA, QUEREMOS, DESDE LA ESTACI\u00d3N DE NEGURI, FELICITAROS LAS FIESTAS Y DESEAROS SUERTE EN TODO LO (bueno) QUE OS PROPONG\u00c1IS. <\/p>\n<p>Adem\u00e1s, os informamos de algunas cositas:<br \/>\n1)ESTE MEDIOD\u00cdA DEL 24 DE DICIEMBRE, HABR\u00c1 UN APERITIVO ESPECIAL EN LA ESTACI\u00d3N DE NEGURI, CON PINTXOS DE BOGAVANTE, CARACOLILLOS Y PULPO COCIDO POR NOSOTROS, MEJILLONES CON NUESTRA SALSA DE TOMATE\u2026 Y NUESTROS HABITUALES PINTXOS DE TORTILLA, SANDWICHES DE TODA CLASE, ENSALADILLA RUSA, BOCADILLITOS DE JAM\u00d3N IB\u00c9RICO\u2026<\/p>\n<p>2)SIGUE COLGADA EN NUESTRAS PAREDES LA EXPO DE LAS FOTOS DE BRUNO FERN\u00c1NDEZ, deber\u00edas verla, es una gozada.<\/p>\n<p>3)EL PR\u00d3XIMO MARTES, 30 DE DICIEMBRE, TENDREMOS UN ACTO MUY ESPECIAL: Ricardo Lez\u00f3n, l\u00edder de la mejor banda pop-rock en castellano, MCENROE, presentar\u00e1 su primer libro de poes\u00edas en nuestro local. Hablaremos de ello, pero os adelantamos dos detalles: ser\u00e1 el d\u00eda 30, martes, en torno a las siete o siete y media de la tarde, y m\u00e1s que probablemente habr\u00e1 lectura de poemas del libro y s\u00ed, tambi\u00e9n un poco de M\u00daSICA EN VIVO, a cargo del propio Ricardo y quiz\u00e1 del alg\u00fan miembro de Mcenroe, banda que como sab\u00e9is publicar\u00e1 dentro de menos de un par de meses su esperad\u00edsimo nuevo disco, \u201cRugen las flores\u201d.<\/p>\n<p>Pues nada m\u00e1s, no tenemos tiempo para hablar de los disgustos que nos da \u00faltimamente el ATHLETIC, ni de las sensaciones que nos vienen a la cabeza al pensar que veremos a la HERMANA del Rey sentarse en el banquillo de los acusados, ni de la decepci\u00f3n que nos causan, cada d\u00eda pol\u00edticos, empresarios, sindicalistas, periodistas y toda la tropa, e incluso la gente de PODEMOS cada vez que se evaden como lagartijas en busca de mejor sol cuando se les pide que concreten sus propuestas (lo del mitin en y sobre Catalunya del otro d\u00eda fue de traca) y pisen tierra de una vez: necesitamos saber lo que supondr\u00eda votarles, caso de que se nos ocurriera, claro.<\/p>\n<p>Lo dicho, os dejamos, cit\u00e1ndoos para el aperitivo de este mediod\u00eda en La estaci\u00f3n y dese\u00e1ndoos FELICES FIESTAS, y lo hacemos con \u201cMontreal\u201d, una de nuestras canciones favoritas de MCENROE, publicada en su segundo disco, \u201cMundo marino\u201d, cuando a\u00fan eran poco m\u00e1s que una sorpresa\/promesa del pop nacional:<\/p>\n<p><iframe loading=\"lazy\" width=\"420\" height=\"315\" src=\"\/\/www.youtube.com\/embed\/3JcZW1Bolf8\" frameborder=\"0\" allowfullscreen><\/iframe><\/p>\n","protected":false},"excerpt":{"rendered":"<p>VIERNES 24 DE DICIEMBRE, EL D\u00cdA DE NOCHEBUENA, QUEREMOS, DESDE LA ESTACI\u00d3N DE NEGURI, FELICITAROS LAS FIESTAS Y DESEAROS SUERTE EN TODO LO (bueno) QUE OS PROPONG\u00c1IS. Adem\u00e1s, os informamos de algunas cositas: 1)ESTE MEDIOD\u00cdA DEL 24 DE DICIEMBRE, HABR\u00c1 &hellip; <a href=\"http:\/\/www.laestaciondeneguri.com\/blog\/desde-la-estacion-felices-fiestas\/\">Sigue leyendo <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[1],"tags":[],"_links":{"self":[{"href":"http:\/\/www.laestaciondeneguri.com\/blog\/wp-json\/wp\/v2\/posts\/497"}],"collection":[{"href":"http:\/\/www.laestaciondeneguri.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.laestaciondeneguri.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.laestaciondeneguri.com\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/www.laestaciondeneguri.com\/blog\/wp-json\/wp\/v2\/comments?post=497"}],"version-history":[{"count":2,"href":"http:\/\/www.laestaciondeneguri.com\/blog\/wp-json\/wp\/v2\/posts\/497\/revisions"}],"predecessor-version":[{"id":500,"href":"http:\/\/www.laestaciondeneguri.com\/blog\/wp-json\/wp\/v2\/posts\/497\/revisions\/500"}],"wp:attachment":[{"href":"http:\/\/www.laestaciondeneguri.com\/blog\/wp-json\/wp\/v2\/media?parent=497"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.laestaciondeneguri.com\/blog\/wp-json\/wp\/v2\/categories?post=497"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.laestaciondeneguri.com\/blog\/wp-json\/wp\/v2\/tags?post=497"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}