{"id":328,"date":"2014-03-21T11:01:32","date_gmt":"2014-03-21T10:01:32","guid":{"rendered":"http:\/\/www.laestaciondeneguri.com\/blog\/?p=328"},"modified":"2014-03-21T11:03:11","modified_gmt":"2014-03-21T10:03:11","slug":"la-mara-y-gus-en-la-estacion","status":"publish","type":"post","link":"http:\/\/www.laestaciondeneguri.com\/blog\/la-mara-y-gus-en-la-estacion\/","title":{"rendered":"La Mara y Gus en La estaci\u00f3n"},"content":{"rendered":"<p>HOY TENEMOS EN LA ESTACI\u00d3N A LA MARA Y GUS, que har\u00e1n flamenquito pop, rumbas, coplas y en este plan. Este a\u00fan nuevo d\u00fao vizca\u00edno factura un elegante flamenco pop, con la impresionante voz de Ainara (una belleza, natural de Leioa) y el toque preciso de Gustavo Borja (de Santzurtzi) a la guitarra. Har\u00e1n un set muy animado y compuesto de versiones de rumbas y canciones de flamenco ligero conocidas por todo el mundo y que, seguro, pondr\u00e1n a bailar a m\u00e1s de una\/o. Pero para quienes gustan del lado m\u00e1s jondo del flamenco, tambi\u00e9n caer\u00e1n buler\u00edas y tangos, incluso alg\u00fan fandango. Escucharemos, en el concierto de LA MARA Y GUS, canciones popularizadas por Rosario, Vanesa Martin, Bambino, Marc Anthony, Manzanita, Ni\u00f1a Pastori&#8230;, todo un fest\u00edn.<br \/>\nLo mejor, sin duda, volver\u00e1 a ser la FANT\u00c1STICA VOZ de La Mara, que visit\u00f3 (con enorme \u00e9xito) hace poco m\u00e1s de un a\u00f1o La Estaci\u00f3n de Neguri. Conocemos, por tanto, el pa\u00f1o. Tras este recital (diciembre de 2012), acompa\u00f1ada entonces por el maestro Heredia, escribimos sobre ella lo que sigue (y por algo ser\u00eda): \u00abHizo La Mara versiones muy personales y de gran calidad de cl\u00e1sicos como \u201cA mi manera\u201d o \u00abNoches de bohemia\u201d, y tambi\u00e9n de canciones m\u00e1s recientes y aflamencadas como \u201cSobrevivir\u00e9\u201d o \u201cArr\u00e1ncame\u201d, adem\u00e1s de alg\u00fan fandango, un par de sevillanas y otro de rumbas. Aunque todo el espect\u00e1culo ray\u00f3 a gran altura y la impecable voz de La Mara funciona en cualesquiera tonos y estilos, de puro bella, n\u00edtida y potente que es (ya nos lo hab\u00eda comentado el maestro Pepe Heredia: \u201cvoz limpia, c\u00e1lida y natural; ha pillado el duende\u201d), nos quedamos con las canciones m\u00e1s lentas y rom\u00e1nticas, que las borda esta pedazo de artista, hasta el punto de que vimos m\u00e1s de una l\u00e1grima de emoci\u00f3n que no pod\u00eda contenerse en el rostro de varios amigos y amigas, y nos inclu\u00edmos absolutamente. Porque no solo canta bien esta joven mujer que brilla en todos los palos del flamenco que abord\u00f3, sino que trasmite toneladas de intensa emoci\u00f3n cuando canta e irradia una simpat\u00eda y naturalidad de enamorar, adem\u00e1s de comportarse en todo momento como una artista hecha y derecha en el escenario. (&#8230;) Lo tiene todo: talento y duende flamenco, belleza, juventud, encanto natural&#8230;\u00bb.<br \/>\nPara su concierto de ESTE VIERNES 21 DE MARZO, A LAS NUEVE DE LA NOCHE, en La Estaci\u00f3n de Neguri, y seg\u00fan ella misma nos ha comentado, La Mara ha elegido un repertorio animado y bailable y frecuentar\u00e1 m\u00e1s los \u00abpalos\u00bb ligeros, como la rumba y el flamenco\/pop.<br \/>\nHar\u00e1n canciones como esta \u00abA\u00fan no te has ido\u00bb que interpreta en este video en directo Vanesa Martin. A las nueve, en La Estaci\u00f3n, en Neguri, LA MARA Y GUS. Si te gustan Estrella Morente, Rosario, Vanesa Martin, Bambino, Marc Anthony, Manzanita, Ni\u00f1a Pastori&#8230; ya est\u00e1s viniendo. <\/p>\n<p><iframe loading=\"lazy\" width=\"560\" height=\"315\" src=\"\/\/www.youtube.com\/embed\/_RQF-6dvo2A\" frameborder=\"0\" allowfullscreen><\/iframe><\/p>\n","protected":false},"excerpt":{"rendered":"<p>HOY TENEMOS EN LA ESTACI\u00d3N A LA MARA Y GUS, que har\u00e1n flamenquito pop, rumbas, coplas y en este plan. Este a\u00fan nuevo d\u00fao vizca\u00edno factura un elegante flamenco pop, con la impresionante voz de Ainara (una belleza, natural de &hellip; <a href=\"http:\/\/www.laestaciondeneguri.com\/blog\/la-mara-y-gus-en-la-estacion\/\">Sigue leyendo <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[59],"tags":[240,247,235,233,246,249,237,231,234,248,66,242,241,243,244,238,232,245,236,239],"_links":{"self":[{"href":"http:\/\/www.laestaciondeneguri.com\/blog\/wp-json\/wp\/v2\/posts\/328"}],"collection":[{"href":"http:\/\/www.laestaciondeneguri.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.laestaciondeneguri.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.laestaciondeneguri.com\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/www.laestaciondeneguri.com\/blog\/wp-json\/wp\/v2\/comments?post=328"}],"version-history":[{"count":2,"href":"http:\/\/www.laestaciondeneguri.com\/blog\/wp-json\/wp\/v2\/posts\/328\/revisions"}],"predecessor-version":[{"id":330,"href":"http:\/\/www.laestaciondeneguri.com\/blog\/wp-json\/wp\/v2\/posts\/328\/revisions\/330"}],"wp:attachment":[{"href":"http:\/\/www.laestaciondeneguri.com\/blog\/wp-json\/wp\/v2\/media?parent=328"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.laestaciondeneguri.com\/blog\/wp-json\/wp\/v2\/categories?post=328"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.laestaciondeneguri.com\/blog\/wp-json\/wp\/v2\/tags?post=328"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}