{"id":234,"date":"2013-11-04T14:28:15","date_gmt":"2013-11-04T13:28:15","guid":{"rendered":"http:\/\/www.laestaciondeneguri.com\/blog\/?p=234"},"modified":"2013-11-04T14:28:15","modified_gmt":"2013-11-04T13:28:15","slug":"un-momento-magico-en-el-homenaje-a-lou-reed","status":"publish","type":"post","link":"http:\/\/www.laestaciondeneguri.com\/blog\/un-momento-magico-en-el-homenaje-a-lou-reed\/","title":{"rendered":"Un momento m\u00e1gico en el homenaje a Lou Reed"},"content":{"rendered":"<p>UN MOMENTO M\u00c1GICO DEL PASADO VERNES, EN EL HOMENAJE A LOU REED. Hubo este primer viernes de noviembre, en el inolvidable concierto homenaje a Lou Reed en La Estaci\u00f3n, varios momentos m\u00e1gicos que quedar\u00e1n adheridos para siempre a la parte feliz de nuestra memoria. Cada uno lo fue a su estilo, apelando a una emotividad y a un estado de \u00e1nimo distintos. Y es que como se hicieron temas tan variados en forma y concepto y que fueron grabados desde los primeros a\u00f1os 70 hasta finales de los 80, pues hubo de todo. Desde las vanguardistas y psicotr\u00f3picas canciones de Velvet Underground &#038; (la misteriosa y embriagadora) Nico, hasta las sedosas, m\u00edticas y majestuosas composiciones de un joven Lou a\u00fan casi en los inicios de su carrera en solitario, pasando por las m\u00e1s rockeras y febrilentas, que ha facturado desde sus inicios hasta finales de los 80, y que te impiden pensar en nada que no sea moverte y disfrutar de un buen plato de proteico rock, del que alimenta eso que llevamos siglos buscando c\u00f3mo denominar y que tiene un metabolismo tan especial, tan distinto que nos equipara a otros animales. Ufff, a d\u00f3nde nos ha llevado terminar esta frase\u2026, la verdad es que no tenemos ni idea de escribir.<\/p>\n<p>Volviendo a los momentos m\u00e1gicos del concierto del viernes, si tuvi\u00e9ramos que elegir uno por rockero, marchoso y potente -imposible pararse quieto-, quiz\u00e1 ser\u00eda el que la fenomenal banda montada por Lu\u00eds Echevarria para este evento protagoniz\u00f3 interpretando \u201cDirty Boulevard\u201d (del disco \u201cNew York\u201d de 1989 ), uan canci\u00f3n que costar\u00eda incluir entre las m\u00e1s gloriosas del autor neoyorkino, pero que nos aturde y conquista irremisiblemente con esos impresionantes guitarrazos, el vozarr\u00f3n de Lou y esa bater\u00eda por momentos demoledora. Todav\u00eda lo recordamos, como si hubiera sido hace una hora: viernes noche, casi al final del concierto, con el sonido a tope y los cuerpos del respetable, sobre todo en las primeras filas, en tensi\u00f3n y movimiento, plenos de dicha y de energ\u00eda, como nos gusta a nosotros. Feliz domingo, y no dej\u00e9iss de pasaros por La Estaci\u00f3n.<br \/>\n<iframe loading=\"lazy\" width=\"560\" height=\"315\" src=\"\/\/www.youtube.com\/embed\/7z3TPwOT31g\" frameborder=\"0\" allowfullscreen><\/iframe><\/p>\n","protected":false},"excerpt":{"rendered":"<p>UN MOMENTO M\u00c1GICO DEL PASADO VERNES, EN EL HOMENAJE A LOU REED. Hubo este primer viernes de noviembre, en el inolvidable concierto homenaje a Lou Reed en La Estaci\u00f3n, varios momentos m\u00e1gicos que quedar\u00e1n adheridos para siempre a la parte &hellip; <a href=\"http:\/\/www.laestaciondeneguri.com\/blog\/un-momento-magico-en-el-homenaje-a-lou-reed\/\">Sigue leyendo <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[1],"tags":[],"_links":{"self":[{"href":"http:\/\/www.laestaciondeneguri.com\/blog\/wp-json\/wp\/v2\/posts\/234"}],"collection":[{"href":"http:\/\/www.laestaciondeneguri.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.laestaciondeneguri.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.laestaciondeneguri.com\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/www.laestaciondeneguri.com\/blog\/wp-json\/wp\/v2\/comments?post=234"}],"version-history":[{"count":1,"href":"http:\/\/www.laestaciondeneguri.com\/blog\/wp-json\/wp\/v2\/posts\/234\/revisions"}],"predecessor-version":[{"id":235,"href":"http:\/\/www.laestaciondeneguri.com\/blog\/wp-json\/wp\/v2\/posts\/234\/revisions\/235"}],"wp:attachment":[{"href":"http:\/\/www.laestaciondeneguri.com\/blog\/wp-json\/wp\/v2\/media?parent=234"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.laestaciondeneguri.com\/blog\/wp-json\/wp\/v2\/categories?post=234"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.laestaciondeneguri.com\/blog\/wp-json\/wp\/v2\/tags?post=234"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}