{"id":212,"date":"2013-09-03T13:19:15","date_gmt":"2013-09-03T12:19:15","guid":{"rendered":"http:\/\/www.laestaciondeneguri.com\/blog\/?p=212"},"modified":"2013-09-03T13:19:15","modified_gmt":"2013-09-03T12:19:15","slug":"martes-de-septiembre-soleado-y-con-buenas-noticias","status":"publish","type":"post","link":"http:\/\/www.laestaciondeneguri.com\/blog\/martes-de-septiembre-soleado-y-con-buenas-noticias\/","title":{"rendered":"Martes de septiembre, soleado y con buenas noticias"},"content":{"rendered":"<p>MARTES, SOLEADO Y CON BUENAS NOTICIAS. Sobrevivimos ayer bonitamente al primer lunes de setiembre y hoy nos despertamos con pron\u00f3stico de un d\u00eda espl\u00e9ndido, soleado y caluroso, y con tres noticias positivas: <\/p>\n<p>1) Ocurri\u00f3 el milagro y el EUSKATEL no desaparecer\u00e1 (la iron\u00eda es que quien lo ha salvado\/comprado es el piloto Fernando Alonso, que no goza precisamente de muchas simpat\u00edas en tierras vascas, quiiz\u00e1 hasta hoy, porque lo que ha hecho tiene m\u00e9rito. \u00bfpodr\u00e1 el equipo seguir siendo un emblema del ciclismo vasco? Lo dudamos, pero habr\u00e1 que esperar acontecimientos. <\/p>\n<p>2) HERRERA SE QUEDA en el Athletic, y estamos contentos pero duele que, m\u00e1s que probablemente, este chico -tan correcto, inteligente, educado y sensato en todo- haya sido utilizado por el Manchester para abaratar la compra de otro jugador por el que estaba negociando y que finalmente ha acabado fichando. No es normal -\u00bfni admisible?- que pase lo de ayer (cuando ya se cre\u00eda que el fichaje estaba hecho, con el dinero encima de la mesa, de pronto se desmorona todo), parece una pantomima, no es serio. Lo sentimos por Ander, nos alegramos por nosotros.<\/p>\n<p>3) LA ECONOM\u00cdA da un m\u00ednimo respiro (buena cifra de paro de agosto, sube la Bolsa, datos mcaroecon\u00f3micos&#8230;) y alimenta la esperanza en la mejora. Solo eso, solo se para la ca\u00edda (dice el Gobierno), aunque si creemos a otros (Borrell, pej.) seguimos hundidos en la miseria y decir lo contrario equivale a enga\u00f1ar a la gente. Es importante no seguir empeorando pero queremos comenzar a ver signos inequ\u00edvocos de recuperaci\u00f3n, lo necesitamos. <\/p>\n<p>La noticia curiosa del d\u00eda es que el solar ocupado por una m\u00edtica DISCOTECA bilbaina, la deustoarra GARDEN, cerrada hace pocos a\u00f1os tras un lento declinar del negocio, alberga desde ayer a un gran supermercado, que por cierto y aunque se antoje bien triste cambiar espacios de ocio por otros de mera intendencia-, le vendr\u00e1 muy bien a los vecinos del barrio, no sobrando de superficies comerciales.<\/p>\n<p>Y continuando con las cosas del comer, sorprendente y pol\u00e9mica la decision del gobierno griego -con el fin de abaratar la cesta de la compra de las familias empobrecidas, la mayor\u00eda tras varios a\u00f1os de graves crisis econ\u00f3mica y social- de admitir la VENTA DE ALIMENTOS CADUCADOS (en realidad, de productos con fecha de consumo preferente -que no es lo mismo que la de caducidad, m\u00e1s estricta y peligrosa- superada). \u00bfLlegaremos aqu\u00ed a esto, estamos tan mal? \u00bfRealmente la medida supone un riesgo sanitario para la poblaci\u00f3n? y si no, \u00bfa qu\u00e9 esperamos; qu\u00e9 estamos haciendo, con esta crisis que padecemos, tirar comida \u00fatil que tanto necesitan miles de hogares? Interesante asunto para el debate, porque quiz\u00e1 ha llegado, tambi\u00e9n aqu\u00ed, el momento de dejar atr\u00e1s falsos pudores e ir a lo pr\u00e1ctico, a lo contingente, que dir\u00eda el otro. <\/p>\n<p>Comentaros una cosita: que este VIERNES, SI TODO SALE BIEN, EL PROGRAMA DE LA ESTACI\u00d3N VA SER DE A\u00daPA. El concierto de THE BANDS, con su jam session (vete preparando, afina esa guitarra que ten\u00edas enfundada desde hace a\u00f1os, y ves, de paso, entonando y cuidando un poco la voz) est\u00e1 confirmado, pero podr\u00edamos albergar otro evento art\u00edstico (muy) importante ese mismo d\u00eda. Os tendremos informados. Recordad apuntar la fecha en la agenda.<\/p>\n<p>Va, la m\u00fasica. Hoy os dejamos con los tejanos (son de Austin) OKKERVIL RIVER, banda que hace seis o siete a\u00f1os nos encantaba con su mezcla de americana y pop british, m\u00fasica indie emocionante sin renunciar a cierta comercialidad, y que llegamos a ver -con buen resultado- en directo dos veces (Barcelona en el Primavera Sound y Castell\u00f3n, en el selecto Tanned Tin). Lo que ocurre es que con el paso del tiempo, y de la publicaci\u00f3n de discos, ha convertido en un grupo que hace music agradable y bonita, un pop-rock elegante, animado, sin sorpresas y de impecable factura, pero sin m\u00e1s, como se dice ahora; si bien hay que subrayar que LA VOZ de su l\u00edder, Will Shef, nos sigue pareciendo casi perfecta, e id\u00f3nea para el rock suave y de toques \u00e9picos que han acabado produciendo. Al tema, se llama \u00abDown Down The Deep River\u00bb y es el tercer corte (y quiz\u00e1 el mejor de todos) del nuevo disco de OKKERVIL RIVER, de t\u00edtulo \u00abThe Silver Gymnasium\u00bb.<\/p>\n<p><iframe loading=\"lazy\" width=\"420\" height=\"315\" src=\"\/\/www.youtube.com\/embed\/7mjb0V9IgGI\" frameborder=\"0\" allowfullscreen><\/iframe><\/p>\n","protected":false},"excerpt":{"rendered":"<p>MARTES, SOLEADO Y CON BUENAS NOTICIAS. Sobrevivimos ayer bonitamente al primer lunes de setiembre y hoy nos despertamos con pron\u00f3stico de un d\u00eda espl\u00e9ndido, soleado y caluroso, y con tres noticias positivas: 1) Ocurri\u00f3 el milagro y el EUSKATEL no &hellip; <a href=\"http:\/\/www.laestaciondeneguri.com\/blog\/martes-de-septiembre-soleado-y-con-buenas-noticias\/\">Sigue leyendo <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[1],"tags":[],"_links":{"self":[{"href":"http:\/\/www.laestaciondeneguri.com\/blog\/wp-json\/wp\/v2\/posts\/212"}],"collection":[{"href":"http:\/\/www.laestaciondeneguri.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.laestaciondeneguri.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.laestaciondeneguri.com\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/www.laestaciondeneguri.com\/blog\/wp-json\/wp\/v2\/comments?post=212"}],"version-history":[{"count":1,"href":"http:\/\/www.laestaciondeneguri.com\/blog\/wp-json\/wp\/v2\/posts\/212\/revisions"}],"predecessor-version":[{"id":213,"href":"http:\/\/www.laestaciondeneguri.com\/blog\/wp-json\/wp\/v2\/posts\/212\/revisions\/213"}],"wp:attachment":[{"href":"http:\/\/www.laestaciondeneguri.com\/blog\/wp-json\/wp\/v2\/media?parent=212"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.laestaciondeneguri.com\/blog\/wp-json\/wp\/v2\/categories?post=212"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.laestaciondeneguri.com\/blog\/wp-json\/wp\/v2\/tags?post=212"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}