{"id":199,"date":"2013-06-28T14:36:24","date_gmt":"2013-06-28T13:36:24","guid":{"rendered":"http:\/\/www.laestaciondeneguri.com\/blog\/?p=199"},"modified":"2013-06-28T14:36:24","modified_gmt":"2013-06-28T13:36:24","slug":"dos-sugerencias-literarias","status":"publish","type":"post","link":"http:\/\/www.laestaciondeneguri.com\/blog\/dos-sugerencias-literarias\/","title":{"rendered":"Dos sugerencias literarias"},"content":{"rendered":"<p>UNA NOVELA QUE OS SUGERIMOS, por infinidad de razones, una de ellas, ayuda a comprender c\u00f3mo fueron y como son y c\u00f3mo funcionan las cosas en EEUU: se trata de \u00abPastoral americana\u00bb, de PHILIP ROTH, uno de nuestros tres o cuatro escritores vivos favoritos. Se public\u00f3 en 1997, ha sido multipremiada y es una de sus obras de referencia pero a\u00fan no la hab\u00edamos le\u00eddo. Y es que tiene fama de un poco pe\u00f1azo. Craso error. Imprescindible, tanto como pensador como por escritor, ROTH es un animal enfurecido describiendo sus muy veros\u00edmiles pero poli\u00e9dricos personajes, un cirujano que prepara la operaci\u00f3n minuciosamente, analiza la enfermedad con lucidez, objetividad y humanidad, intenta comprenderla, se la explica al paciente, y despu\u00e9s deja el protocolo del consentimiento informado a enfermo y familiares en la camilla para que lo firmen, y en un momento de distracci\u00f3n se va y les deja all\u00ed solos, porque en realidad la cura de la enfermedad est\u00e1 en sus manos y no en la del sistema sanitario. Dura, implacable, muy cr\u00edtica pero a la vez indulgente con la forma de vida y el pensamiento jud\u00edos, la novela cuenta la vida de una familia de Newark en los a\u00f1os previos y posteriores a la guerra de Vietnam, pero en realidad el tema que aborda es la vida misma: la influencia de la religi\u00f3n en nuestro imaginario, el peso de los padres en la manera de ser de los hijos, el sue\u00f1o americano de libertad y de hacerse rico, el cambio del canon moral que se produjo a parte de los a\u00f1os 50, la falsedad y los secretos inconfesables que sobrevuelan sobre las relaciones de pareja m\u00e1s asentadas, la desorientaci\u00f3n de los adolescentes, la hipocres\u00eda de las relaciones personales en esas urbes deshumanizadas donde impera el juego de las apariencias y la competencia m\u00e1s descarnada, la soledad del individuo como \u00fanica verdad existencial incontrovertible, las penalidades de la adolescencia, y quiz\u00e1 sobre todo&#8230; Las ideolog\u00edas como absoluto imperfecto y frustrante que al igual que las religiones, al pretender erigirse sobre lo humano y explicar lo inexplicable generan no solo ac\u00f3litos y proselitistas sino seguidores descerebrados y fan\u00e1ticos que se aferran a ese acogedor sistema cerrado de ideas para acallar sus miedos y hallar un hueco m\u00ednimamente confortable en el mundo y acaban haciendo cualquier desprop\u00f3sito y m\u00e1s locos que una cabra. Si crees que el ser humano tiene alma , y que es m\u00e0s conciencia que ciencia, esta \u00abPASTORAL AMERICANA\u00bb debe ser tu novela para ese verano. No te divertir\u00e1s mucho, es m\u00e1s bien triste y pesimista, aunque literariamente es casi inmejorable. Te apasionar\u00e1 y te desvelar\u00e1 esas cosas sobre ti mismo, sobre los dem\u00e1s y tus relaciones con ellos que cierto d\u00eda comenzaste a preferir ignorar, porque quiz\u00e1s en eso consiste hacer mayor. Porque ROTH es el gran analista de la sociedad actual, el escritor total, universal, el que mejor describe el desconcierto y la insatisfacci\u00f3n en que estamos sumidos, tomados en cuenta uno a uno, a pesar de que te\u00f3ricamente vivamos en el mejor de los mundos que el ser humano ha sido capaz de desarrollar en toda su historia sobre el planeta.<\/p>\n<p>Otra sugerencia, esta (por la log\u00edstica, que no por otra cosa) menos sencilla y econ\u00f3mica que la de leer una novela muy f\u00e1cil de encontrar. Se trata de LA EXPOSICI\u00d3N DE CAMILLE PISSARRO, UNO LOS PUNTALES DEL IMPRESIONISMO, EN EL THYSSEN, EN MADRID. Es un personaje que siempre nos hab\u00eda interesado, por su peripecia vital (era de ideas anarquistas, a finales del s. XIX, por ejemplo) y, claro, porque sus cuadros (paisajes campestres,y urbanos en la \u00faltima fase de su vida) siempre nos hab\u00edan gustado. El problema era que s\u00f3lo hab\u00edamos tenido oportunidad de ver en vivo no m\u00e1s de un par de docenas de cuadros de PISSARRO y repartidos en varios museos de diversas ciudades del mundo. Pues bien, esta del Thyssen es probablemente la Expo definitiva (los cuadros han sido prestados por museos de todo el mundos)) sobre este autor no tan reconocido como merece, que hay que ver, con casi 80 obras de todas las \u00e9pocas del artista. Conocemos la obra de coet\u00e1neos de PISSARRO, como Cezanne, Monet, Degas, Renoir, Gauguin o el propio Van Gogh, y os aseguramos que la de PISSARRO es tan valiosa como la de ellos, y genera tanta o m\u00e1s emoci\u00f3n y satisfacci\u00f3n al espectador. Esta es una de esas exposiciones que Justifica el viaje a Madrid, no lo dud\u00e9is.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>UNA NOVELA QUE OS SUGERIMOS, por infinidad de razones, una de ellas, ayuda a comprender c\u00f3mo fueron y como son y c\u00f3mo funcionan las cosas en EEUU: se trata de \u00abPastoral americana\u00bb, de PHILIP ROTH, uno de nuestros tres o &hellip; <a href=\"http:\/\/www.laestaciondeneguri.com\/blog\/dos-sugerencias-literarias\/\">Sigue leyendo <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[1],"tags":[],"_links":{"self":[{"href":"http:\/\/www.laestaciondeneguri.com\/blog\/wp-json\/wp\/v2\/posts\/199"}],"collection":[{"href":"http:\/\/www.laestaciondeneguri.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.laestaciondeneguri.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.laestaciondeneguri.com\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/www.laestaciondeneguri.com\/blog\/wp-json\/wp\/v2\/comments?post=199"}],"version-history":[{"count":1,"href":"http:\/\/www.laestaciondeneguri.com\/blog\/wp-json\/wp\/v2\/posts\/199\/revisions"}],"predecessor-version":[{"id":200,"href":"http:\/\/www.laestaciondeneguri.com\/blog\/wp-json\/wp\/v2\/posts\/199\/revisions\/200"}],"wp:attachment":[{"href":"http:\/\/www.laestaciondeneguri.com\/blog\/wp-json\/wp\/v2\/media?parent=199"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.laestaciondeneguri.com\/blog\/wp-json\/wp\/v2\/categories?post=199"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.laestaciondeneguri.com\/blog\/wp-json\/wp\/v2\/tags?post=199"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}