{"id":1125,"date":"2017-10-03T11:26:01","date_gmt":"2017-10-03T10:26:01","guid":{"rendered":"http:\/\/www.laestaciondeneguri.com\/blog\/?p=1125"},"modified":"2017-10-03T11:26:20","modified_gmt":"2017-10-03T10:26:20","slug":"fallece-tom-petty","status":"publish","type":"post","link":"http:\/\/www.laestaciondeneguri.com\/blog\/fallece-tom-petty\/","title":{"rendered":"Fallece Tom Petty"},"content":{"rendered":"<p>Las palabras enormes y las grandes ideas nos han ido quedando cada vez m\u00e1s grandes y ajenas, solo crean guerras, desencuentros, fractura social y tensiones; nuestra patria mas sentida es -y lo es cada vez m\u00e1s- la familia, los amigos, la naturaleza\/los paisajes y los recuerdos. Y, c\u00f3mo no, la music en general y el rock en particular, y dentro de ella, la obra de genios que convirtieron nuestra vida en m\u00e1s grande, emocionante y disfrutable. Todo esto ya nos provee a algunos de un sentimiento de pertenencia suficiente, quiz\u00e1 no haga falta m\u00e1s<\/p>\n<p>Esta pasada noche ha muerto TOM PETTY, v\u00edctima de un infarto. Nunca lleg\u00f3 a tocar en Espa\u00f1a; no llegamos a verle en directo ni lo haremos ya jam\u00e1s. La \u00faltima oportunidad viable fue Londres hace pocas semanas, pero no pudimos ir, por motivos bien sencillos. Buenos amigos nuestros hicieron el esfuerzo y le vieron, afortunados ellos. Leemos que \u00abPetty estaba en la recta final de una gran gira para celebrar los 40 a\u00f1os de su carrera junto a la banda de acompa\u00f1amiento de toda su vida, The Heartbreakers\u00bb.<br \/>\nEsta canci\u00f3n ha sonado un mill\u00f3n de veces en La Estaci\u00f3n de Neguri. Hoy lo har\u00e1 tambi\u00e9n, al igual que otras muchas del fant\u00e1stico repertorio de este icono del rock norteamericano m\u00e1s aut\u00e9ntico y menos rendido a las tentaciones del dinero y la fama.<br \/>\nHorror de comienzo de mes.<\/p>\n<p><iframe loading=\"lazy\" src=\"https:\/\/www.youtube.com\/embed\/-p1jtVunLE4\" width=\"560\" height=\"315\" frameborder=\"0\" allowfullscreen=\"allowfullscreen\"><\/iframe><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Las palabras enormes y las grandes ideas nos han ido quedando cada vez m\u00e1s grandes y ajenas, solo crean guerras, desencuentros, fractura social y tensiones; nuestra patria mas sentida es -y lo es cada vez m\u00e1s- la familia, los amigos, &hellip; <a href=\"http:\/\/www.laestaciondeneguri.com\/blog\/fallece-tom-petty\/\">Sigue leyendo <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[887],"tags":[1358,493],"_links":{"self":[{"href":"http:\/\/www.laestaciondeneguri.com\/blog\/wp-json\/wp\/v2\/posts\/1125"}],"collection":[{"href":"http:\/\/www.laestaciondeneguri.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.laestaciondeneguri.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.laestaciondeneguri.com\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/www.laestaciondeneguri.com\/blog\/wp-json\/wp\/v2\/comments?post=1125"}],"version-history":[{"count":1,"href":"http:\/\/www.laestaciondeneguri.com\/blog\/wp-json\/wp\/v2\/posts\/1125\/revisions"}],"predecessor-version":[{"id":1126,"href":"http:\/\/www.laestaciondeneguri.com\/blog\/wp-json\/wp\/v2\/posts\/1125\/revisions\/1126"}],"wp:attachment":[{"href":"http:\/\/www.laestaciondeneguri.com\/blog\/wp-json\/wp\/v2\/media?parent=1125"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.laestaciondeneguri.com\/blog\/wp-json\/wp\/v2\/categories?post=1125"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.laestaciondeneguri.com\/blog\/wp-json\/wp\/v2\/tags?post=1125"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}