{"id":1017,"date":"2017-02-16T09:20:35","date_gmt":"2017-02-16T08:20:35","guid":{"rendered":"http:\/\/www.laestaciondeneguri.com\/blog\/?p=1017"},"modified":"2017-02-16T09:22:21","modified_gmt":"2017-02-16T08:22:21","slug":"charla-en-la-facultad-de-periodismo","status":"publish","type":"post","link":"http:\/\/www.laestaciondeneguri.com\/blog\/charla-en-la-facultad-de-periodismo\/","title":{"rendered":"Charla en la facultad de periodismo"},"content":{"rendered":"<p>Ayer, MARTES, invitado por unos excompa\u00f1eros de trabajo (si no, de qu\u00e9, je) en Eroski y en ETB, VOLV\u00cd A LA UNIVERSIDAD, campus de Leioa, facultad de Periodismo, Comunicaci\u00f3n y tal.<\/p>\n<p>Recuerdos buenos y peores iban arremetiendo a cada paso contra nuestro precario equilibrio emocional; tantos a\u00f1os sin pasar por all\u00ed, sin sentir el ambiente de una universidad plagada de j\u00f3venes, sin ver los despachos de los profesores&#8230;, y, para rematar la dosis de nostalgia, el motivo de la visita fue dar una conferencia que giraba sobre la actividad profesional a la que dediqu\u00e9 25 (en su mayor parte, gozosos) a\u00f1os de mi vida; resumiendo, el t\u00edtulo de la charla era: \u00abPresente y futuro de la informaci\u00f3n sobre consumo y vida cotidiana\u00bb. Me refiero a informar con rigor, calidad t\u00e9cnica y objetividad sobre asuntos tan de hoy y se siempre como los de las preferentes o las cl\u00e1usulas suelo y en general los abusos de la banca, la nutrici\u00f3n y sus falsos mitos, la factura energ\u00e9tica, los servicios sanitarios, el transporte y los viajes, los comedores escolares, el impacto medioambiental de nuestro modo de vida&#8230;, en fin&#8230;, lo de cada d\u00eda.<\/p>\n<p>Puse bastante negra la cosa:<\/p>\n<p>&#8211; medios de comunicaci\u00f3n (p\u00fablicos y privados) cada vez m\u00e1s dependientes de la publicidad institucional y de las grandes empresas; imposible financiar programas o investigaciones que cuestionen, con datos veraces y de peso, lo que dice la publicidad de esas grandes marcas y los servicios prestados por los poderes p\u00fablicos.<\/p>\n<p>&#8211; una ciudadan\u00eda que se ha acostumbrado a no pagar por informarse; ya casi nadie compra peri\u00f3dicos, por ejemplo.<\/p>\n<p>&#8211; la banalizaci\u00f3n, reina del cotarro. Tenemos una sociedad cada vez m\u00e1s cotilla y trivial, que a los medios de comunicaci\u00f3n les pide fundamentalmente entretenimiento, y no informaci\u00f3n rigurosa y \u00fatil.<\/p>\n<p>Y, a modo de puntilla, quiz\u00e1 no deb\u00ed hacerlo, les dije a los chicos y chicas (eran de primero, es decir, poco m\u00e1s de 18 a\u00f1os) que si ellos, los periodistas del futuro no pagaban por la informaci\u00f3n (reconocieron con pasmosa naturalidad que no compraban peri\u00f3dicos, y que ni siquiera los le\u00edan; su fuente para informarse era Internet; se siente, Facebook y redes sociales y ocasionalmente alg\u00fan diario digital, si eso), c\u00f3mo pod\u00edan confiar en que otras personas lo hicieran cuando ellos buscaran trabajo.<\/p>\n<p>En fin, que una vez m\u00e1s, animando a la pe\u00f1a. Eso s\u00ed, fue un bonito reencuentro con el pasado reciente y no tan reciente.<\/p>\n<p>Os dejamos con nuestro \u00faltimo descubrimiento: se llama MITSKI, es joven y japonesa, vive en Nueva York tras haberlo hecho en Congo, Malasia, China y Turqu\u00eda; su disco es de 2.016 y nos pas\u00f3 inadvertido como, bien seguro, ocurri\u00f3 con tantos otros discos valiosos. Comparte MITSKI selllo discogr\u00e1fico (Dead Oceans) con artistas amados por nosotros como Phosphorescent y Kevin Morby, o sea que tampoco es casual el tema. Ha sido definida esta nueva chica joya del folk-rock como cruce entre Courtney Barnett y Mazzy Star, lo que indica bastante sobre su ubicaci\u00f3n estil\u00edstica.<\/p>\n<p><iframe loading=\"lazy\" width=\"560\" height=\"315\" src=\"https:\/\/www.youtube.com\/embed\/u_hDHm9MD0I\" frameborder=\"0\" allowfullscreen><\/iframe><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ayer, MARTES, invitado por unos excompa\u00f1eros de trabajo (si no, de qu\u00e9, je) en Eroski y en ETB, VOLV\u00cd A LA UNIVERSIDAD, campus de Leioa, facultad de Periodismo, Comunicaci\u00f3n y tal. Recuerdos buenos y peores iban arremetiendo a cada paso &hellip; <a href=\"http:\/\/www.laestaciondeneguri.com\/blog\/charla-en-la-facultad-de-periodismo\/\">Sigue leyendo <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[46,887],"tags":[1281,1283,649,1225,1284,1286,1285,1282,605,1060],"_links":{"self":[{"href":"http:\/\/www.laestaciondeneguri.com\/blog\/wp-json\/wp\/v2\/posts\/1017"}],"collection":[{"href":"http:\/\/www.laestaciondeneguri.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.laestaciondeneguri.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.laestaciondeneguri.com\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/www.laestaciondeneguri.com\/blog\/wp-json\/wp\/v2\/comments?post=1017"}],"version-history":[{"count":1,"href":"http:\/\/www.laestaciondeneguri.com\/blog\/wp-json\/wp\/v2\/posts\/1017\/revisions"}],"predecessor-version":[{"id":1018,"href":"http:\/\/www.laestaciondeneguri.com\/blog\/wp-json\/wp\/v2\/posts\/1017\/revisions\/1018"}],"wp:attachment":[{"href":"http:\/\/www.laestaciondeneguri.com\/blog\/wp-json\/wp\/v2\/media?parent=1017"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.laestaciondeneguri.com\/blog\/wp-json\/wp\/v2\/categories?post=1017"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.laestaciondeneguri.com\/blog\/wp-json\/wp\/v2\/tags?post=1017"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}